{"id":1031,"date":"2022-05-09T13:18:51","date_gmt":"2022-05-09T13:18:51","guid":{"rendered":"https:\/\/turismonoar.com.br\/?p=1031"},"modified":"2022-05-09T13:21:47","modified_gmt":"2022-05-09T13:21:47","slug":"dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor","status":"publish","type":"post","link":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/","title":{"rendered":"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor"},"content":{"rendered":"\n<p>O Brasil celebrou neste domingo (08.05) o <strong>Dia Nacional <\/strong>de um dos setores mais impactados pela pandemia no Brasil, mas que, com apoio decisivo do governo federal, vive um momento de retomada e exibe forte poder de recupera\u00e7\u00e3o. Trata-se do Turismo, segmento que, gradualmente, volta a experimentar n\u00fameros condizentes com a impon\u00eancia de uma atividade transversal a mais de 50 diferentes ramos da economia em todo o pa\u00eds.<\/p>\n\n\n\n<p>As evid\u00eancias do desempenho positivo se baseiam em dados recentes. Segundo a Ag\u00eancia Nacional de Avia\u00e7\u00e3o Civil (ANAC), por exemplo, 6,4 milh\u00f5es de passageiros viajaram em voos nacionais durante o m\u00eas de mar\u00e7o, o dobro do mesmo per\u00edodo de 2021. Tamb\u00e9m em mar\u00e7o, a Associa\u00e7\u00e3o Brasileira de Ag\u00eancias de Viagens Corporativas (ABRACORP) apurou um faturamento total de R$ 869 milh\u00f5es na \u00e1rea, apenas 2% inferior ao do mesmo m\u00eas em 2019.<\/p>\n\n\n\n<p>O ministro do Turismo, Carlos Brito, elogia os esfor\u00e7os do trade tur\u00edstico frente aos desafios e refor\u00e7a o compromisso com o pleno restabelecimento do setor. \u201cO apoio do governo Bolsonaro e o comprometimento do trade foram fundamentais para preservar atividades e preparar a retomada. Os resultados nos motivam a trabalhar para permitir que o turismo volte aos n\u00edveis pr\u00e9-pandemia e contribua cada vez mais com a economia e a gera\u00e7\u00e3o de emprego e renda\u201d, frisa.<\/p>\n\n\n\n<p>Outra mostra favor\u00e1vel vem do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE): o \u00edndice de atividades tur\u00edsticas no pa\u00eds cresceu 29% no primeiro bimestre em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2021 &#8211; isso depois de avan\u00e7ar 21% ao longo do ano passado, na compara\u00e7\u00e3o com 2020. Por sinal, filiados \u00e0 Associa\u00e7\u00e3o Brasileira de Ag\u00eancias de Viagens (ABAV) fecharam 2021 com receitas totais de R$ 19,3 bilh\u00f5es, um aumento de 37,6% em rela\u00e7\u00e3o a 2020.<\/p>\n\n\n\n<p>Desde o in\u00edcio da pandemia, o Minist\u00e9rio do Turismo adotou v\u00e1rias a\u00e7\u00f5es para mitigar efeitos negativos. Entre elas, a Medida Provis\u00f3ria 936 que garantiu sal\u00e1rios e redu\u00e7\u00e3o de jornadas; MPs que definiram regras quanto ao cancelamento e \u00e0 remarca\u00e7\u00e3o de servi\u00e7os; a oferta de R$ 5 bilh\u00f5es em cr\u00e9dito, o repasse de R$ 3 bilh\u00f5es a a\u00e7\u00f5es emergenciais na cultura e a disponibiliza\u00e7\u00e3o do Selo Turismo Respons\u00e1vel, que indica o cumprimento de medidas de preven\u00e7\u00e3o \u00e0 Covid.<\/p>\n\n\n\n<p>O ministro Carlos Brito ressalta que a ado\u00e7\u00e3o de protocolos de biosseguran\u00e7a, aliada a avan\u00e7os na vacina\u00e7\u00e3o contra o coronav\u00edrus promovida pelo governo federal, refor\u00e7am o ambiente prop\u00edcio \u00e0 realiza\u00e7\u00e3o de viagens no pa\u00eds. \u201cO nosso grande objetivo foi garantir a sobreviv\u00eancia de atividades em todo o Brasil para que voc\u00ea, turista, possa usufruir do melhor que os nossos diversos destinos t\u00eam a oferecer em termos de experi\u00eancias memor\u00e1veis\u201d, justifica.<\/p>\n\n\n\n<p><strong>ESTRUTURA\u00c7\u00c3O<\/strong>&nbsp;&#8211; A adequada prepara\u00e7\u00e3o do setor para a retomada tamb\u00e9m recebeu aten\u00e7\u00e3o. No ano passado, o MTur registrou a entrega de 762 obras de infraestrutura apoiadas pelo \u00f3rg\u00e3o no pa\u00eds, com um aporte de R$ 866,2 milh\u00f5es. Houve avan\u00e7os, ainda, por parte do Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (IPHAN), vinculado ao \u00f3rg\u00e3o. Desde 2019, a autarquia soma a finaliza\u00e7\u00e3o de 70 obras de recupera\u00e7\u00e3o de espa\u00e7os hist\u00f3ricos, alvo de investimentos de R$ 290 milh\u00f5es.<\/p>\n\n\n\n<p>Outra importante medida foi a defini\u00e7\u00e3o do novo Mapa do Turismo Brasileiro que orienta pol\u00edticas p\u00fablicas e investimentos do MTur em todo o territ\u00f3rio nacional. A ferramenta passou a reunir 2.644 cidades, distribu\u00eddas por 336 regi\u00f5es tur\u00edsticas, sendo que, partir deste ano, o seu desenho conta com um aprimoramento: o Mapa pode ser atualizado a qualquer momento, e n\u00e3o mais a cada dois anos, permitindo que mais munic\u00edpios integrem o instrumento.<\/p>\n\n\n\n<p>A fim de incentivar a realiza\u00e7\u00e3o de viagens pelo brasileiro no pa\u00eds, o Minist\u00e9rio do Turismo lan\u00e7ou neste ano o Programa + Cr\u00e9dito + Turismo. A iniciativa, uma parceria com a Caixa Econ\u00f4mica Federal, facilita o cr\u00e9dito consignado e assegura amplo parcelamento para que servidores p\u00fablicos federais e aposentados e pensionistas do INSS adquiram servi\u00e7os em empreendimentos como ag\u00eancias de turismo e meios de hospedagem.<\/p>\n\n\n\n<p>Os esfor\u00e7os do MTur tamb\u00e9m passaram pelo fortalecimento do turismo n\u00e1utico. Al\u00e9m de articular junto ao governo federal a retomada da atual temporada &#8211; que, apesar dos efeitos da pandemia, deve movimentar mais de R$ 1 bilh\u00e3o e gerar cerca de 14 mil empregos &#8211; o \u00f3rg\u00e3o deu in\u00edcio neste ano a um grande pacote de a\u00e7\u00f5es de incentivo que envolve medidas como a isen\u00e7\u00e3o de impostos, a oferta de cr\u00e9dito e a melhoria da infraestrutura n\u00e1utica.<\/p>\n\n\n\n<p>O MTur concretizou, ainda, o Programa Turismo Seguro, que busca desenvolver a\u00e7\u00f5es e pol\u00edticas p\u00fablicas para ampliar a sensa\u00e7\u00e3o de bem-estar dos visitantes no pa\u00eds. Pioneira, a iniciativa contempla 59 a\u00e7\u00f5es, divididas em eixos de atua\u00e7\u00e3o que envolvem a seguran\u00e7a p\u00fablica, a preven\u00e7\u00e3o \u00e0 explora\u00e7\u00e3o sexual de crian\u00e7as e adolescentes no turismo, as rela\u00e7\u00f5es de consumo no setor, o transporte tur\u00edstico, a defesa civil, a vigil\u00e2ncia sanit\u00e1ria e a comunica\u00e7\u00e3o positiva.<\/p>\n\n\n\n<p>Atento \u00e0 necessidade de se garantir bom atendimento a visitantes, o Minist\u00e9rio do Turismo qualificou 34 mil profissionais em 2021, por meio de capacita\u00e7\u00f5es gratuitas. O \u00f3rg\u00e3o tamb\u00e9m disponibilizou um m\u00e9todo inovador de comunica\u00e7\u00e3o em l\u00edngua inglesa a trabalhadores do ramo. Baseado no ensino de express\u00f5es b\u00e1sicas do idioma por meio de v\u00eddeos, o \u201cWould You Like\u201d permite que trabalhadores com baixa escolaridade aprimorem a comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>A atra\u00e7\u00e3o do interesse de grandes players mundiais do setor pelo Brasil \u00e9 outra prioridade do \u00f3rg\u00e3o. O Portal de Investimentos do Minist\u00e9rio do Turismo, que re\u00fane oportunidades de atua\u00e7\u00e3o privada no pa\u00eds, j\u00e1 acumula um portf\u00f3lio de 65 projetos de empreendimentos tur\u00edsticos em 19 estados e no Distrito Federal. Juntos, eles somam aproximadamente R$ 26 bilh\u00f5es em aportes privados previstos e podem abrir mais de 125 mil empregos.<\/p>\n\n\n\n<p>A Pasta tamb\u00e9m trabalha para transformar localidades do pa\u00eds em espa\u00e7os mais adaptados ao futuro do setor. Um projeto-piloto de cria\u00e7\u00e3o de Destinos Tur\u00edsticos Inteligentes (DTI) re\u00fane duas cidades representando cada uma das cinco regi\u00f5es do pa\u00eds: Rio Branco\/AC e Palmas\/TO (Norte); Recife\/PE e Salvador\/BA (Nordeste); Campo Grande\/MS e Bras\u00edlia\/DF (Centro-Oeste); Florian\u00f3polis\/SC e Curitiba\/PR (Sul); Rio de Janeiro\/RJ e Angra dos Reis\/RJ (Sudeste).<\/p>\n\n\n\n<p>O ministro do Turismo avalia que as a\u00e7\u00f5es empreendidas pelo governo Jair Bolsonaro fortalecem a percep\u00e7\u00e3o do Brasil como um destino promissor. \u201cO nosso empenho em assegurar o total aproveitamento do imenso potencial do pa\u00eds \u00e9 reconhecido, inclusive, pela mais alta entidade internacional do setor, a Organiza\u00e7\u00e3o Mundial do Turismo, que prepara a instala\u00e7\u00e3o no Brasil do seu primeiro escrit\u00f3rio regional das Am\u00e9ricas\u201d, salienta Carlos Brito.<\/p>\n\n\n\n<p><strong>VISIBLIDADE<\/strong>&nbsp;&#8211; A consolida\u00e7\u00e3o da retomada na \u00e1rea tamb\u00e9m envolve esfor\u00e7os pela promo\u00e7\u00e3o de atributos nacionais no exterior, com vistas ao crescimento da chegada de visitantes estrangeiros ao pa\u00eds. Apoiada pelo MTur, a Embratur (Ag\u00eancia Brasileira de Promo\u00e7\u00e3o Internacional do Turismo) divulga, desde 2019, o fim da exig\u00eancia de vistos para o ingresso no Brasil de viajantes australianos, canadenses, japoneses e norte-americanos.<\/p>\n\n\n\n<p>Dados divulgados recentemente apontam bons resultados quanto ao desembarque de estrangeiros no Brasil. Nos primeiros dois meses deste ano, conforme o Sistema de Tr\u00e1fego Internacional da Pol\u00edcia Federal, mais de 530 mil visitantes vieram ao pa\u00eds. E n\u00fameros do Banco Central revelam que o gasto deste p\u00fablico no Brasil somou US$ 781 milh\u00f5es em janeiro e fevereiro, uma alta de 63% na compara\u00e7\u00e3o com o mesmo bimestre de 2021 (US$ 480 milh\u00f5es).<\/p>\n\n\n\n<p>O presidente da Embratur, Silvio Nascimento, aposta no fortalecimento da imagem do Brasil. \u201cEstamos caminhando para a retomada total do setor e estes dados refor\u00e7am que o Brasil \u00e9 um destino interessante e seguro. Nos Estados Unidos, por exemplo, a nossa campanha sobre a isen\u00e7\u00e3o de vistos contribuiu para a gera\u00e7\u00e3o de US$ 5,7 milh\u00f5es em vendas ao pa\u00eds. O trabalho conjunto com o MTur certamente vai aumentar o n\u00famero de estrangeiros no Brasil ao longo do ano\u201d, prev\u00ea.<\/p>\n\n\n\n<p>At\u00e9 o final deste ano, a Embratur tem na sua agenda a realiza\u00e7\u00e3o de pelo menos quatro campanhas publicit\u00e1rias nos Estados Unidos, na Europa e na Am\u00e9rica Latina, bem como a organiza\u00e7\u00e3o de famtours, press trips e roadshows, entre outras a\u00e7\u00f5es. A Ag\u00eancia tamb\u00e9m deve se fazer presente em 14 grandes feiras do segmento no exterior e, ainda, aproveitar a visibilidade da Copa do Mundo da Fifa, no Catar, para organizar a\u00e7\u00f5es de promo\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>SOBRE A DATA<\/strong>&nbsp;&#8211; O Dia Nacional do Turismo foi institu\u00eddo em 2012, com a san\u00e7\u00e3o da Lei 12.625. A data \u00e9 uma refer\u00eancia a 8 de maio de 1916, quando o estado do Paran\u00e1 solicitou que terras junto \u00e0s Cataratas do Igua\u00e7u fossem desapropriadas e declaradas de utilidade p\u00fablica para a cria\u00e7\u00e3o de um parque. A demanda foi acatada em 28 de julho de 1916, com o Decreto Estadual n\u00ba 653. Hoje, a unidade recebe milh\u00f5es de turistas e constitui um \u00edcone do turismo nacional.<\/p>\n\n\n\n<p>MTur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil celebrou neste domingo (08.05) o Dia Nacional de um dos setores mais impactados pela pandemia no Brasil, mas<\/p>\n","protected":false},"author":1,"featured_media":1034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[82],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor - Turismo no Ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor - Turismo no Ar\" \/>\n<meta property=\"og:description\" content=\"O Brasil celebrou neste domingo (08.05) o Dia Nacional de um dos setores mais impactados pela pandemia no Brasil, mas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo no Ar\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T13:18:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T13:21:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"X3C6tkkG0W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismonoar.com.br\/#website\",\"url\":\"https:\/\/turismonoar.com.br\/\",\"name\":\"Turismo no Ar\",\"description\":\"Por Paulo Lopes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismonoar.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png\",\"contentUrl\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png\",\"width\":768,\"height\":434},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#webpage\",\"url\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/\",\"name\":\"Dia Nacional do Turismo: uma homenagem \\u00e0 resili\\u00eancia do setor - Turismo no Ar\",\"isPartOf\":{\"@id\":\"https:\/\/turismonoar.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#primaryimage\"},\"datePublished\":\"2022-05-09T13:18:51+00:00\",\"dateModified\":\"2022-05-09T13:21:47+00:00\",\"author\":{\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\"},\"breadcrumb\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/turismonoar.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia Nacional do Turismo: uma homenagem \\u00e0 resili\\u00eancia do setor\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\",\"name\":\"X3C6tkkG0W\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"caption\":\"X3C6tkkG0W\"},\"sameAs\":[\"http:\/\/turismonoar.com.br\"],\"url\":\"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor - Turismo no Ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor - Turismo no Ar","og_description":"O Brasil celebrou neste domingo (08.05) o Dia Nacional de um dos setores mais impactados pela pandemia no Brasil, mas","og_url":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/","og_site_name":"Turismo no Ar","article_published_time":"2022-05-09T13:18:51+00:00","article_modified_time":"2022-05-09T13:21:47+00:00","og_image":[{"width":768,"height":434,"url":"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png","path":"\/home\/turismo\/public_html\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png","size":"full","id":1034,"alt":"","pixels":333312,"type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"X3C6tkkG0W","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/turismonoar.com.br\/#website","url":"https:\/\/turismonoar.com.br\/","name":"Turismo no Ar","description":"Por Paulo Lopes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismonoar.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png","contentUrl":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/Calcadao-do-Jacare-JPA.png","width":768,"height":434},{"@type":"WebPage","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#webpage","url":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/","name":"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor - Turismo no Ar","isPartOf":{"@id":"https:\/\/turismonoar.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#primaryimage"},"datePublished":"2022-05-09T13:18:51+00:00","dateModified":"2022-05-09T13:21:47+00:00","author":{"@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22"},"breadcrumb":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/09\/dia-nacional-do-turismo-uma-homenagem-a-resiliencia-do-setor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/turismonoar.com.br\/"},{"@type":"ListItem","position":2,"name":"Dia Nacional do Turismo: uma homenagem \u00e0 resili\u00eancia do setor"}]},{"@type":"Person","@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22","name":"X3C6tkkG0W","image":{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","caption":"X3C6tkkG0W"},"sameAs":["http:\/\/turismonoar.com.br"],"url":"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/"}]}},"cc_featured_image_caption":{"caption_text":"Cal\u00e7ad\u00e3o da Praia do Jacar\u00e9, em Cabedelo (PB). Cr\u00e9dito: Cacio Murilo\/MTur Destinos.","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1031"}],"collection":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1031"}],"version-history":[{"count":1,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1031\/revisions"}],"predecessor-version":[{"id":1033,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1031\/revisions\/1033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/1034"}],"wp:attachment":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}