{"id":1073,"date":"2022-05-23T12:55:01","date_gmt":"2022-05-23T12:55:01","guid":{"rendered":"https:\/\/turismonoar.com.br\/?p=1073"},"modified":"2022-05-23T12:55:04","modified_gmt":"2022-05-23T12:55:04","slug":"rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york","status":"publish","type":"post","link":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/","title":{"rendered":"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York"},"content":{"rendered":"\n<p>Nos dias 19 e 20 de maio, o Estado do Rio Grande do Norte, por meio da Empresa Potiguar de Promo\u00e7\u00e3o Tur\u00edstica (Emprotur), participou da etapa presencial do Re-think South America Travel Show, na cidade de Nova York, Estados Unidos.<\/p>\n\n\n\n<p>A feira, patrocinada pela Latam Airlines, foi voltada para relacionamento e promo\u00e7\u00e3o de mercados da Am\u00e9rica do Sul e o Rio Grande do Norte foi o \u00fanico estado brasileiro presente, dando prosseguimento \u00e0s a\u00e7\u00f5es que est\u00e3o sendo ativadas para posicionar o destino no mercado norte-americano junto aos operadores, agentes de viagens e DMC\u2019s<\/p>\n\n\n\n<p>A expectativa da Emprotur \u00e9 que os resultados j\u00e1 possam ser percebidos em m\u00e9dio prazo. \u201cEstamos abrindo esse canal de prospec\u00e7\u00e3o visando \u00e0 diversifica\u00e7\u00e3o dos nossos mercados emissores. Temos um destino consolidado tanto na Am\u00e9rica do Sul quanto na Europa e queremos trabalhar essa janela de oportunidade apresentada nos Estados Unidos, onde nos apresentamos como uma nova op\u00e7\u00e3o de viagem, um destino tend\u00eancia\u201d, comentou o diretor-presidente da Emprotur, Bruno Reis.<\/p>\n\n\n\n<p>De acordo com dados do setor de intelig\u00eancia da Emprotur, antes da pandemia o Brasil recebia em m\u00e9dia mais de 550 mil turistas dos Estados Unidos por ano, aproximadamente 8% do total de estrangeiros que visitam o pa\u00eds. A escolha desse mercado como novo p\u00fablico alvo se justifica pela relev\u00e2ncia para o setor de viagens e turismo no Brasil, onde n\u00e3o h\u00e1 exig\u00eancia de visto para que os americanos possam viajar aos nossos destinos.<\/p>\n\n\n\n<p>Paralelamente a participa\u00e7\u00e3o no Re-think, foi lan\u00e7ado no mercado norte-americano na \u00faltima quarta-feira (18) material audiovisual atualizado e exclusivo sobre o destino, com uma linguagem espec\u00edfica para as demandas desse mercado. Dessa forma, os principais players est\u00e3o sendo alcan\u00e7ados por meio de mat\u00e9rias, reportagens, releases e ativa\u00e7\u00f5es digitais.<\/p>\n\n\n\n<p>Os representantes da Emprotur no evento tamb\u00e9m tiveram agenda com a Associa\u00e7\u00e3o dos Operadores de Viagens dos Estados Unidos (USTOA). Na pauta, as possibilidades de neg\u00f3cios e vendas do destino.<\/p>\n\n\n\n<p>Setur\/RN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos dias 19 e 20 de maio, o Estado do Rio Grande do Norte, por meio da Empresa Potiguar de<\/p>\n","protected":false},"author":1,"featured_media":1074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar\" \/>\n<meta property=\"og:description\" content=\"Nos dias 19 e 20 de maio, o Estado do Rio Grande do Norte, por meio da Empresa Potiguar de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo no Ar\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-23T12:55:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-23T12:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"X3C6tkkG0W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismonoar.com.br\/#website\",\"url\":\"https:\/\/turismonoar.com.br\/\",\"name\":\"Turismo no Ar\",\"description\":\"Por Paulo Lopes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismonoar.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg\",\"contentUrl\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg\",\"width\":1140,\"height\":641},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#webpage\",\"url\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/\",\"name\":\"RN foi o \\u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar\",\"isPartOf\":{\"@id\":\"https:\/\/turismonoar.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#primaryimage\"},\"datePublished\":\"2022-05-23T12:55:01+00:00\",\"dateModified\":\"2022-05-23T12:55:04+00:00\",\"author\":{\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\"},\"breadcrumb\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/turismonoar.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RN foi o \\u00fanico estado brasileiro a participar do Re-think South America em Nova York\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\",\"name\":\"X3C6tkkG0W\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"caption\":\"X3C6tkkG0W\"},\"sameAs\":[\"http:\/\/turismonoar.com.br\"],\"url\":\"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/","og_locale":"pt_BR","og_type":"article","og_title":"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar","og_description":"Nos dias 19 e 20 de maio, o Estado do Rio Grande do Norte, por meio da Empresa Potiguar de","og_url":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/","og_site_name":"Turismo no Ar","article_published_time":"2022-05-23T12:55:01+00:00","article_modified_time":"2022-05-23T12:55:04+00:00","og_image":[{"width":1140,"height":641,"url":"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg","path":"\/home\/turismo\/public_html\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg","size":"full","id":1074,"alt":"","pixels":730740,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"X3C6tkkG0W","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/turismonoar.com.br\/#website","url":"https:\/\/turismonoar.com.br\/","name":"Turismo no Ar","description":"Por Paulo Lopes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismonoar.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg","contentUrl":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2022\/05\/3f71147c-a990-428f-984e-f39d1943d0db-1140x641-1.jpg","width":1140,"height":641},{"@type":"WebPage","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#webpage","url":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/","name":"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York - Turismo no Ar","isPartOf":{"@id":"https:\/\/turismonoar.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#primaryimage"},"datePublished":"2022-05-23T12:55:01+00:00","dateModified":"2022-05-23T12:55:04+00:00","author":{"@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22"},"breadcrumb":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turismonoar.com.br\/index.php\/2022\/05\/23\/rn-foi-o-unico-estado-brasileiro-a-participar-do-re-think-south-america-em-nova-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/turismonoar.com.br\/"},{"@type":"ListItem","position":2,"name":"RN foi o \u00fanico estado brasileiro a participar do Re-think South America em Nova York"}]},{"@type":"Person","@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22","name":"X3C6tkkG0W","image":{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","caption":"X3C6tkkG0W"},"sameAs":["http:\/\/turismonoar.com.br"],"url":"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/"}]}},"cc_featured_image_caption":{"caption_text":"Emprotur ativou o destino nos Estados Unidos em mais uma parceria com a Latam. Foto. Divulga\u00e7\u00e3o.","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1073"}],"collection":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":1,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"predecessor-version":[{"id":1075,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1073\/revisions\/1075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}