{"id":1882,"date":"2023-04-04T12:11:34","date_gmt":"2023-04-04T12:11:34","guid":{"rendered":"https:\/\/turismonoar.com.br\/?p=1882"},"modified":"2023-04-04T12:11:36","modified_gmt":"2023-04-04T12:11:36","slug":"mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur","status":"publish","type":"post","link":"https:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/","title":{"rendered":"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur"},"content":{"rendered":"\n<p>Estudo foi divulgado nesta segunda-feira (03.04), na WTM Latin America, umas das maiores feiras do setor tur\u00edstico mundial. Pasta tamb\u00e9m apresentou mapeamento de atrativos acess\u00edveis pelo pa\u00eds.<br>Mais da metade (53,5%) dos turistas com defici\u00eancia deixaram de viajar para algum destino no pa\u00eds por falta de acessibilidade. Foi o que apontou um mapeamento in\u00e9dito sobre o Perfil do Turista com Defici\u00eancia, lan\u00e7ado pelo Minist\u00e9rio do Turismo nesta segunda-feira (03.04) durante a WTM Latin America. De acordo com o estudo, a maioria deste p\u00fablico tem idade entre 41 e 50 anos (24,3%), \u00e9 da regi\u00e3o Sudeste (49,1%), e s\u00e3o mulheres (64,4%). Al\u00e9m disso, 49% deles disseram viajar sempre acompanhados.<br>\u201cNo Brasil, cerca de 17 milh\u00f5es de pessoas possuem algum tipo de defici\u00eancia. S\u00e3o brasileiros que querem e merecem viajar e conhecer as belezas do nosso pa\u00eds, com presta\u00e7\u00e3o de servi\u00e7os e atendimento de qualidade\u201d, afirmou a ministra do Turismo, Daniela Carneiro, que, ap\u00f3s participar de reuni\u00e3o ministerial em Bras\u00edlia, tamb\u00e9m participou da WTM.<br>Al\u00e9m do Perfil do Turista com Defici\u00eancia, o Minist\u00e9rio do Turismo lan\u00e7ou tamb\u00e9m o Mapeamento de Atrativos, Empreendimentos, Produtos e Servi\u00e7os Acess\u00edveis, que re\u00fane atrativos tur\u00edsticos brasileiros com acessibilidade para pessoas com defici\u00eancia ou mobilidade reduzida. Ambas as publica\u00e7\u00f5es t\u00eam como objetivos orientar prestadores de servi\u00e7os e profissionais do setor para que possam conhecer a realidade desse p\u00fablico, se adaptarem e melhorarem as experi\u00eancias de atendimento para pessoas com defici\u00eancia e mobilidade reduzida, al\u00e9m de oferecerem op\u00e7\u00f5es de destinos que j\u00e1 s\u00e3o acess\u00edveis como boas pr\u00e1ticas tur\u00edsticas.<br>Desenvolvido em parceria com a Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura (UNESCO), os mapeamentos j\u00e1 est\u00e3o dispon\u00edveis no portal do MTur e podem ser acessados por prestadores, empreendedores, profissionais e estudantes de turismo, al\u00e9m dos pr\u00f3prios turistas e interessados no tema.<br>Conhe\u00e7a os detalhes sobre cada um dos Mapeamentos:<br>ATRATIVOS E EMPREENDIMENTOS &#8211; O Mapeamento de Atrativos, Empreendimentos, Produtos e Servi\u00e7os Acess\u00edveis \u00e9 um portf\u00f3lio on-line com orienta\u00e7\u00f5es gerais e espec\u00edficas para cada tipo de atrativo tur\u00edstico, listando o tipo de defici\u00eancia e como esses atrativos devem se adaptar para receber bem os turistas. A partir das adapta\u00e7\u00f5es, a ideia \u00e9 possibilitar que os visitantes com defici\u00eancia possam usufruir da atividade tur\u00edstica com seguran\u00e7a e autonomia.<br>O Mapeamento da Acessibilidade foi realizado por meio de formul\u00e1rio respondido por empresas que ofertem produtos ou servi\u00e7os tur\u00edsticos. Tamb\u00e9m foram realizadas pesquisas na internet junto a empres\u00e1rios e demais interessados que desenvolvem ou usufruem do turismo acess\u00edvel.<br>Na pesquisa, foram identificados 276 empreendimentos, produtos e servi\u00e7os nas cinco regi\u00f5es que j\u00e1 se estruturaram para receber turistas com algum tipo de defici\u00eancia. S\u00e3o parques, balne\u00e1rios, museus, restaurantes etc. Ao todo, 22 deles est\u00e3o na regi\u00e3o Norte, 35 na regi\u00e3o Centro-Oeste, 46 no Nordeste, 73 na regi\u00e3o Sul e 100 na regi\u00e3o Sudeste.<br>PERFIL DO TURISTA COM DEFICI\u00caNCIA &#8211; O Perfil do Turista tamb\u00e9m est\u00e1 disponibilizado de forma on-line e foi realizado com base em formul\u00e1rio, dessa vez voltado para os turistas com defici\u00eancia, que responderam quest\u00f5es a respeito de como se sentem nos destinos tur\u00edsticos, se j\u00e1 sofreram algum tipo de discrimina\u00e7\u00e3o por conta de sua defici\u00eancia ou mobilidade reduzida, o quanto a acessibilidade influencia na visita\u00e7\u00e3o, entre outros questionamentos.<br>O resultado esperado ap\u00f3s a divulga\u00e7\u00e3o dos mapeamentos \u00e9 que mais de 140 mil prestadores de servi\u00e7os tur\u00edsticos e profissionais da linha de frente possam ser orientados com informa\u00e7\u00f5es e dicas para receber bem as pessoas com defici\u00eancia, com qualidade, seguran\u00e7a e sem discrimina\u00e7\u00e3o.<br>As duas pesquisas ainda receber\u00e3o atualiza\u00e7\u00e3o com informa\u00e7\u00f5es adicionais. O Mapeamento de Atrativos vai contar com mais atrativos e empreendimentos tur\u00edsticos inclu\u00eddos; j\u00e1 o Perfil do Turista com Defici\u00eancia receber\u00e1 dados qualitativos, uma vez que o material vigente traz resultados quantitativos.<br>ATENDIMENTO AO TURISTA &#8211; Durante a WTM, o Minist\u00e9rio do Turismo tamb\u00e9m apresentou uma cartilha atualizada com orienta\u00e7\u00f5es para profissionais que atuam no setor sobre como atender bem pessoas com defici\u00eancia, considerando as necessidades deste perfil de viajante. A publica\u00e7\u00e3o foi desenvolvida em parceria com o Minist\u00e9rio dos Direitos Humanos e da Cidadania.<br>SOBRE O EVENTO &#8211; A WTM Latin America, que completa uma d\u00e9cada em 2023, \u00e9 um dos principais eventos da ind\u00fastria de viagens da regi\u00e3o e tem como tem\u00e1tica, neste ano, \u201cExplore novos horizontes\u201d. Durante os tr\u00eas dias de realiza\u00e7\u00e3o (entre 3 e 5 de abril), s\u00e3o esperados 600 expositores de 45 pa\u00edses diferentes e um p\u00fablico de mais 16 mil pessoas. O Minist\u00e9rio do Turismo \u00e9 um dos patrocinadores da feira e conta com um espa\u00e7o para a divulga\u00e7\u00e3o das a\u00e7\u00f5es e pol\u00edticas p\u00fablicas voltadas ao turismo.<br>MTur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo foi divulgado nesta segunda-feira (03.04), na WTM Latin America, umas das maiores feiras do setor tur\u00edstico mundial. Pasta tamb\u00e9m<\/p>\n","protected":false},"author":1,"featured_media":1883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[191],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar\" \/>\n<meta property=\"og:description\" content=\"Estudo foi divulgado nesta segunda-feira (03.04), na WTM Latin America, umas das maiores feiras do setor tur\u00edstico mundial. Pasta tamb\u00e9m\" \/>\n<meta property=\"og:url\" content=\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo no Ar\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T12:11:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T12:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"X3C6tkkG0W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismonoar.com.br\/#website\",\"url\":\"https:\/\/turismonoar.com.br\/\",\"name\":\"Turismo no Ar\",\"description\":\"Por Paulo Lopes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismonoar.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg\",\"contentUrl\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg\",\"width\":768,\"height\":434},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#webpage\",\"url\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/\",\"name\":\"Mais da metade dos turistas com defici\\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar\",\"isPartOf\":{\"@id\":\"https:\/\/turismonoar.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#primaryimage\"},\"datePublished\":\"2023-04-04T12:11:34+00:00\",\"dateModified\":\"2023-04-04T12:11:36+00:00\",\"author\":{\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\"},\"breadcrumb\":{\"@id\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/turismonoar.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais da metade dos turistas com defici\\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\",\"name\":\"X3C6tkkG0W\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"caption\":\"X3C6tkkG0W\"},\"sameAs\":[\"http:\/\/turismonoar.com.br\"],\"url\":\"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar","og_description":"Estudo foi divulgado nesta segunda-feira (03.04), na WTM Latin America, umas das maiores feiras do setor tur\u00edstico mundial. Pasta tamb\u00e9m","og_url":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/","og_site_name":"Turismo no Ar","article_published_time":"2023-04-04T12:11:34+00:00","article_modified_time":"2023-04-04T12:11:36+00:00","og_image":[{"width":768,"height":434,"url":"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg","path":"\/home\/turismo\/public_html\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg","size":"full","id":1883,"alt":"","pixels":333312,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"X3C6tkkG0W","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/turismonoar.com.br\/#website","url":"https:\/\/turismonoar.com.br\/","name":"Turismo no Ar","description":"Por Paulo Lopes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismonoar.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg","contentUrl":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/04\/Acessibilidade-MTur.jpeg","width":768,"height":434},{"@type":"WebPage","@id":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#webpage","url":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/","name":"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur - Turismo no Ar","isPartOf":{"@id":"https:\/\/turismonoar.com.br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#primaryimage"},"datePublished":"2023-04-04T12:11:34+00:00","dateModified":"2023-04-04T12:11:36+00:00","author":{"@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22"},"breadcrumb":{"@id":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/turismonoar.com.br\/index.php\/2023\/04\/04\/mais-da-metade-dos-turistas-com-deficiencia-deixaram-de-viajar-por-falta-de-acessibilidade-aponta-novo-estudo-do-mtur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/turismonoar.com.br\/"},{"@type":"ListItem","position":2,"name":"Mais da metade dos turistas com defici\u00eancia deixaram de viajar por falta de acessibilidade, aponta novo estudo do MTur"}]},{"@type":"Person","@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22","name":"X3C6tkkG0W","image":{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","caption":"X3C6tkkG0W"},"sameAs":["http:\/\/turismonoar.com.br"],"url":"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/"}]}},"cc_featured_image_caption":{"caption_text":"Cr\u00e9dito: Freepik\r\n","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1882"}],"collection":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1882"}],"version-history":[{"count":1,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1882\/revisions"}],"predecessor-version":[{"id":1884,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1882\/revisions\/1884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/1883"}],"wp:attachment":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}