{"id":2173,"date":"2023-07-29T12:23:38","date_gmt":"2023-07-29T12:23:38","guid":{"rendered":"https:\/\/turismonoar.com.br\/?p=2173"},"modified":"2023-07-29T12:23:40","modified_gmt":"2023-07-29T12:23:40","slug":"governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada","status":"publish","type":"post","link":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/","title":{"rendered":"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada"},"content":{"rendered":"\n<p>O Governo do Rio Grande do Norte, por meio da Secretaria de Estado do Turismo (SETUR\/RN), a Empresa Potiguar de Promo\u00e7\u00e3o Tur\u00edstica (Emprotur) e a Azul Viagens realizaram o lan\u00e7amento da malha a\u00e9rea para a alta temporada. O evento aconteceu nesta sexta-feira (28), \u00e0s 9h da manh\u00e3, no Hotel Escola Senac Barreira Roxa.&nbsp;<\/p>\n\n\n\n<p>Na ocasi\u00e3o, a secret\u00e1ria de Estado do Turismo, Aninha Costa, a diretoria-presidente da Emprotur, Roberta Duarte, a representante da Azul Viagens, Giulliana Mesquita, apresentaram ao trade a malha a\u00e9rea da empresa para a alta temporada. O evento contou com a parceria do Sistema Fecom\u00e9rcio.<\/p>\n\n\n\n<p>No geral, ser\u00e3o 17 novos voos dedicados, totalizando 238 voos no per\u00edodo de segunda quinzena de dezembro at\u00e9 o final de janeiro. Um incremento de 44% comparando com o mesmo per\u00edodo do ano passado. \u201cEsse resultado \u00e9 fruto de um trabalho constante do Estado por meio da Setur e da Emprotur, buscando junto \u00e0s operadoras de turismo ampliar a oferta de voos para os principais mercados emissores de turistas para o nosso destino e realizando campanhas cooperadas de promo\u00e7\u00e3o, capacita\u00e7\u00f5es com agentes de viagens, &nbsp;entre outras a\u00e7\u00f5es. Esses voos dedicados para a alta temporada simbolizam, garantia de trabalho e gera\u00e7\u00e3o de renda para as milhares de pessoas que vivem do turismo potiguar\u201d, ressalta a secret\u00e1ria Aninha Costa.<\/p>\n\n\n\n<p>Os destinos comtemplados s\u00e3o: Confins\/Belo Horizonte, Uberl\u00e2ndia\/Minas Gerais, S\u00e3o Jos\u00e9 do Rio Preto\/S\u00e3o Paulo, Viracopos\/Campinas, Congonhas\/S\u00e3o Paulo, Presidente Prudente\/S\u00e3o Paulo, S\u00e3o Jos\u00e9 dos Pinhais\/Paran\u00e1, Ribeir\u00e3o Preto\/S\u00e3o Paulo, Bel\u00e9m do Par\u00e1\/Par\u00e1, Bauru\/S\u00e3o Paulo e a inaugura\u00e7\u00e3o de um rota in\u00e9dita, para Cascavel\/Paran\u00e1.&nbsp;<\/p>\n\n\n\n<p>De Acordo com Azul Viagens, Natal j\u00e1 recebeu mais de 27.000 turistas pela Azul Viagens. Este valor \u00e9 16% maior que o ano passado no mesmo per\u00edodo, que fechou o ano com 42.000 clientes para o destino.&nbsp;<\/p>\n\n\n\n<p>A diretora-presidente da Emprotur, Roberta Duarte, falou sobre o reflexo para o turismo do RN em raz\u00e3o ao incremento dos voos na malha a\u00e9rea. \u201cA Empresa Potiguar de Promo\u00e7\u00e3o Tur\u00edstica atua com estrat\u00e9gia e dados sobre o mercado, estamos com campanhas cooperadas com todas as companhias a\u00e9reas nacionais e com as principais operadoras. Esse trabalho \u00e9 indispens\u00e1vel para buscar o fluxo de turistas est\u00e1vel ao longo de todo o ano\u201d, explica a nova presidente da Emprotur, Roberta Duarte.<\/p>\n\n\n\n<p>O evento contou com a presen\u00e7a da secretaria de turismo de Natal, Ohana Fernandes, o presidente da Associa\u00e7\u00e3o Brasileira da Ind\u00fastria de Hot\u00e9is (ABIH), Abdon Gosson, Wanderson Borges (Movimento Preserve Pipa), J\u00fanior C\u00e2mara (Sidetur), Michele Pereira (ABAV\/RN), Arthur Fontes (Abrasel\/RN), representantes do trade tur\u00edstico, e entidades do Turismo.<\/p>\n\n\n\n<p>Setur\/RN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo do Rio Grande do Norte, por meio da Secretaria de Estado do Turismo (SETUR\/RN), a Empresa Potiguar de<\/p>\n","protected":false},"author":1,"featured_media":2174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[205],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada - Turismo no Ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada - Turismo no Ar\" \/>\n<meta property=\"og:description\" content=\"O Governo do Rio Grande do Norte, por meio da Secretaria de Estado do Turismo (SETUR\/RN), a Empresa Potiguar de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo no Ar\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-29T12:23:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-29T12:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"X3C6tkkG0W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismonoar.com.br\/#website\",\"url\":\"https:\/\/turismonoar.com.br\/\",\"name\":\"Turismo no Ar\",\"description\":\"Por Paulo Lopes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismonoar.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg\",\"contentUrl\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#webpage\",\"url\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/\",\"name\":\"Governo do RN e Azul Viagens realizam lan\\u00e7amento de malha a\\u00e9rea para a alta temporada - Turismo no Ar\",\"isPartOf\":{\"@id\":\"https:\/\/turismonoar.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#primaryimage\"},\"datePublished\":\"2023-07-29T12:23:38+00:00\",\"dateModified\":\"2023-07-29T12:23:40+00:00\",\"author\":{\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\"},\"breadcrumb\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/turismonoar.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo do RN e Azul Viagens realizam lan\\u00e7amento de malha a\\u00e9rea para a alta temporada\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\",\"name\":\"X3C6tkkG0W\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"caption\":\"X3C6tkkG0W\"},\"sameAs\":[\"http:\/\/turismonoar.com.br\"],\"url\":\"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada - Turismo no Ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada - Turismo no Ar","og_description":"O Governo do Rio Grande do Norte, por meio da Secretaria de Estado do Turismo (SETUR\/RN), a Empresa Potiguar de","og_url":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/","og_site_name":"Turismo no Ar","article_published_time":"2023-07-29T12:23:38+00:00","article_modified_time":"2023-07-29T12:23:40+00:00","og_image":[{"width":1600,"height":1200,"url":"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg","path":"\/home\/turismo\/public_html\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg","size":"full","id":2174,"alt":"","pixels":1920000,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"X3C6tkkG0W","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/turismonoar.com.br\/#website","url":"https:\/\/turismonoar.com.br\/","name":"Turismo no Ar","description":"Por Paulo Lopes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismonoar.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg","contentUrl":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2023\/07\/Nova-malha-aerea-no-RN.jpg","width":1600,"height":1200},{"@type":"WebPage","@id":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#webpage","url":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/","name":"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada - Turismo no Ar","isPartOf":{"@id":"https:\/\/turismonoar.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#primaryimage"},"datePublished":"2023-07-29T12:23:38+00:00","dateModified":"2023-07-29T12:23:40+00:00","author":{"@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22"},"breadcrumb":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turismonoar.com.br\/index.php\/2023\/07\/29\/governo-do-rn-e-azul-viagens-realizam-lancamento-de-malha-aerea-para-a-alta-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/turismonoar.com.br\/"},{"@type":"ListItem","position":2,"name":"Governo do RN e Azul Viagens realizam lan\u00e7amento de malha a\u00e9rea para a alta temporada"}]},{"@type":"Person","@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22","name":"X3C6tkkG0W","image":{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","caption":"X3C6tkkG0W"},"sameAs":["http:\/\/turismonoar.com.br"],"url":"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/"}]}},"cc_featured_image_caption":{"caption_text":"Lan\u00e7amento da malha a\u00e9rea para a alta temporada. Foto. Divulga\u00e7\u00e3o.","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2173"}],"collection":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2173"}],"version-history":[{"count":1,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2173\/revisions"}],"predecessor-version":[{"id":2175,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2173\/revisions\/2175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2174"}],"wp:attachment":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}