{"id":2700,"date":"2024-02-22T15:05:19","date_gmt":"2024-02-22T15:05:19","guid":{"rendered":"https:\/\/turismonoar.com.br\/?p=2700"},"modified":"2024-02-22T15:05:19","modified_gmt":"2024-02-22T15:05:19","slug":"atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro","status":"publish","type":"post","link":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/","title":{"rendered":"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro"},"content":{"rendered":"\n<p>Os participantes do Mapa do Turismo Brasileiro precisam ficar atentos a renova\u00e7\u00e3o anual de seus cadastros para continuar participando da pol\u00edtica p\u00fablica federal! E, para ajudar munic\u00edpios, regi\u00f5es e estados a n\u00e3o perderem esse prazo, o Minist\u00e9rio do Turismo enviar\u00e1, via Sistema de Informa\u00e7\u00f5es do Mapa do Turismo Brasileiro \u2013 SISMAPA 2.0, notifica\u00e7\u00e3o com 60 dias de anteced\u00eancia ao vencimento da data dos registros.<br>A a\u00e7\u00e3o de aprimoramento da estrat\u00e9gia tem o objetivo de conceder mais prazo para que os gestores organizem a documenta\u00e7\u00e3o. \u201cManter o Mapa do Turismo atualizado \u00e9 essencial para a gest\u00e3o do turismo no pa\u00eds, em especial com a retomada do setor a n\u00edvel nacional. S\u00e3o esses dados que nos ajudam a formular pol\u00edticas p\u00fablicas cada vez mais eficazes, capazes de provocar mudan\u00e7as positivas na vida da nossa popula\u00e7\u00e3o\u201d, enfatiza o ministro do Turismo, Celso Sabino.<br>O Mapa do Turismo Brasileiro orienta a defini\u00e7\u00e3o de pol\u00edticas p\u00fablicas, incluindo a destina\u00e7\u00e3o de recursos pelo governo federal para a elabora\u00e7\u00e3o e\/ou revis\u00e3o de planos, estudos e planejamentos visando o fortalecimento da gest\u00e3o descentralizada, obras de infraestrutura tur\u00edstica e oferta de cursos de qualifica\u00e7\u00e3o profissional, por exemplo.<br>O recadastramento anual \u00e9 obrigat\u00f3rio e, desde o ano passado, a plataforma est\u00e1 dispon\u00edvel durante todo o ano para o cadastro de novos destinos.<br>Os cadastros n\u00e3o renovados ap\u00f3s o prazo estipulado, ser\u00e3o automaticamente exclu\u00eddos do Mapa do Turismo Brasileiro. Ap\u00f3s o processo de cadastramento, os gestores podem acompanhar os resultados no site www.mapa.turismo.gov.br e gerar relat\u00f3rios em arquivos Excel, PDF e Dashboard, facilitando a atualiza\u00e7\u00e3o e visualiza\u00e7\u00e3o dos dados.<br>COMO PARTICIPAR &#8211; A participa\u00e7\u00e3o no Mapa \u00e9 aberta a todos os munic\u00edpios brasileiros, desde que observem os crit\u00e9rios estabelecidos em Portaria Ministerial n\u00ba 41\/2021, constru\u00eddos em conjunto com as Unidades da Federa\u00e7\u00e3o. Os estados e o DF podem definir exig\u00eancias complementares, que devem ser igualmente respeitadas.<\/p>\n\n\n\n<p>Fonte. MTur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os participantes do Mapa do Turismo Brasileiro precisam ficar atentos a renova\u00e7\u00e3o anual de seus cadastros para continuar participando da<\/p>\n","protected":false},"author":1,"featured_media":2701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[270],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar\" \/>\n<meta property=\"og:description\" content=\"Os participantes do Mapa do Turismo Brasileiro precisam ficar atentos a renova\u00e7\u00e3o anual de seus cadastros para continuar participando da\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo no Ar\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T15:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"X3C6tkkG0W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismonoar.com.br\/#website\",\"url\":\"https:\/\/turismonoar.com.br\/\",\"name\":\"Turismo no Ar\",\"description\":\"Por Paulo Lopes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismonoar.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg\",\"contentUrl\":\"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg\",\"width\":768,\"height\":434},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#webpage\",\"url\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/\",\"name\":\"Aten\\u00e7\\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar\",\"isPartOf\":{\"@id\":\"https:\/\/turismonoar.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#primaryimage\"},\"datePublished\":\"2024-02-22T15:05:19+00:00\",\"dateModified\":\"2024-02-22T15:05:19+00:00\",\"author\":{\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\"},\"breadcrumb\":{\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/turismonoar.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aten\\u00e7\\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22\",\"name\":\"X3C6tkkG0W\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turismonoar.com.br\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g\",\"caption\":\"X3C6tkkG0W\"},\"sameAs\":[\"http:\/\/turismonoar.com.br\"],\"url\":\"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar","og_description":"Os participantes do Mapa do Turismo Brasileiro precisam ficar atentos a renova\u00e7\u00e3o anual de seus cadastros para continuar participando da","og_url":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/","og_site_name":"Turismo no Ar","article_published_time":"2024-02-22T15:05:19+00:00","og_image":[{"width":768,"height":434,"url":"http:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg","path":"\/home\/turismo\/public_html\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg","size":"full","id":2701,"alt":"","pixels":333312,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"X3C6tkkG0W","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/turismonoar.com.br\/#website","url":"https:\/\/turismonoar.com.br\/","name":"Turismo no Ar","description":"Por Paulo Lopes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismonoar.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg","contentUrl":"https:\/\/turismonoar.com.br\/wp-content\/uploads\/2024\/02\/Mapa-do-Turismo.jpeg","width":768,"height":434},{"@type":"WebPage","@id":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#webpage","url":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/","name":"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro - Turismo no Ar","isPartOf":{"@id":"https:\/\/turismonoar.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#primaryimage"},"datePublished":"2024-02-22T15:05:19+00:00","dateModified":"2024-02-22T15:05:19+00:00","author":{"@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22"},"breadcrumb":{"@id":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turismonoar.com.br\/index.php\/2024\/02\/22\/atencao-gestores-verifiquem-o-prazo-de-recadastramento-no-mapa-do-turismo-brasileiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/turismonoar.com.br\/"},{"@type":"ListItem","position":2,"name":"Aten\u00e7\u00e3o gestores! Verifiquem o prazo de recadastramento no Mapa do Turismo Brasileiro"}]},{"@type":"Person","@id":"https:\/\/turismonoar.com.br\/#\/schema\/person\/052de1f2f2aa889d818e50dd32173c22","name":"X3C6tkkG0W","image":{"@type":"ImageObject","@id":"https:\/\/turismonoar.com.br\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d27a46a9fb82109c8ff4630af358828?s=96&d=mm&r=g","caption":"X3C6tkkG0W"},"sameAs":["http:\/\/turismonoar.com.br"],"url":"https:\/\/turismonoar.com.br\/index.php\/author\/x3c6tkkg0w\/"}]}},"cc_featured_image_caption":{"caption_text":"Neste ano, o MTur ter\u00e1 um servi\u00e7o de alerta que notificar\u00e1 os munic\u00edpios 60 dias antes do vencimento da data. Divulga\u00e7\u00e3o\/Freepik\r\n","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2700"}],"collection":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2700"}],"version-history":[{"count":1,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2700\/revisions"}],"predecessor-version":[{"id":2702,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2700\/revisions\/2702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2701"}],"wp:attachment":[{"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismonoar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}